{"id":438,"date":"2021-04-02T04:38:50","date_gmt":"2021-04-02T04:38:50","guid":{"rendered":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202.jpeg"},"modified":"2021-04-02T04:38:50","modified_gmt":"2021-04-02T04:38:50","slug":"203820b6-bd7f-4a8d-9a5d-ee876ebf6202","status":"inherit","type":"attachment","link":"https:\/\/pancakerecords.de\/index.php\/pay-per-view\/203820b6-bd7f-4a8d-9a5d-ee876ebf6202\/","title":{"rendered":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-438","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-scaled.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-300x300.jpeg 300w, https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1024x1024.jpeg 1024w, https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-150x150.jpeg 150w, https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-768x768.jpeg 768w, https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1536x1536.jpeg 1536w, https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-2048x2048.jpeg 2048w, https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1200x1200.jpeg 1200w, https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1980x1980.jpeg 1980w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":2560,"file":"2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-scaled.jpeg","sizes":{"medium":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-300x300.jpeg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-300x300.jpeg"},"large":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1024x1024.jpeg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1024x1024.jpeg"},"thumbnail":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-150x150.jpeg"},"medium_large":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-768x768.jpeg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-768x768.jpeg"},"1536x1536":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1536x1536.jpeg","width":1536,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1536x1536.jpeg"},"2048x2048":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-2048x2048.jpeg","width":2048,"height":2048,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-2048x2048.jpeg"},"post-thumbnail":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1200x1200.jpeg","width":1200,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1200x1200.jpeg"},"twentytwenty-fullscreen":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1980x1980.jpeg","width":1980,"height":1980,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-1980x1980.jpeg"},"full":{"file":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202-scaled.jpeg","width":2560,"height":2560,"mime_type":"image\/jpeg","source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-scaled.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"203820B6-BD7F-4A8D-9A5D-EE876EBF6202.jpeg"},"post":155,"source_url":"https:\/\/pancakerecords.de\/wp-content\/uploads\/2021\/04\/203820B6-BD7F-4A8D-9A5D-EE876EBF6202-scaled.jpeg","_links":{"self":[{"href":"https:\/\/pancakerecords.de\/index.php\/wp-json\/wp\/v2\/media\/438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pancakerecords.de\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pancakerecords.de\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pancakerecords.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pancakerecords.de\/index.php\/wp-json\/wp\/v2\/comments?post=438"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":155,"href":"https:\/\/pancakerecords.de\/index.php\/wp-json\/wp\/v2\/pages\/155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}